{"id":11750,"date":"2021-02-23T10:43:35","date_gmt":"2021-02-23T02:43:35","guid":{"rendered":"https:\/\/battery9999.com\/de\/?p=11750"},"modified":"2021-02-23T10:43:35","modified_gmt":"2021-02-23T02:43:35","slug":"das-klassische-kettcar-wird-elektrisch","status":"publish","type":"post","link":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/","title":{"rendered":"Das klassische Kettcar wird elektrisch"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11751\" src=\"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg\" alt=\"\" width=\"300\" height=\"176\" \/><!--more--><\/p>\n<p><strong>Die neuen und modernen Kettcars von heute haben mit dem klassischen Tretauto von fr\u00fcher, wie sie einst das Unternehmen Kettler auf den Markt brachte, nicht mehr viel gemeinsam. Geht es nach dem niederl\u00e4ndischen Marktf\u00fchrer Berg Toys, fahren die Kettcars der Zukunft elektrisch.<\/strong><\/p>\n<p><strong>Ede (Niederlande).<\/strong>\u00a0Vier Reifen, ein Sitz knapp \u00fcber dem Boden, zwei Pedalen, eine Kette und ein Lenkrad &#8211; dies sind die wesentlichen Bestandteile des klassischen Kettcars, mit denen in der Vergangenheit Millionen Jungs und M\u00e4dchen die Hofeinfahrten ihrer Eltern oder Gro\u00dfeltern unsicher gemacht haben.<\/p>\n<p>Nach gr\u00f6\u00dferen finanziellen Schwierigkeiten des Unternehmens Kettler, welches damals die ersten Kettcars auf den Markt brachte, wurde die Produktion der Tretautos Ende Januar 2020 endg\u00fcltig eingestellt.<\/p>\n<p>Ganz anders steht das niederl\u00e4ndische Unternehmen Berg Toys aus, welches stets mit der Zeit gegangen ist und immer versucht hat, die Bed\u00fcrfnisse der Kundschaft bei der Konzeption neuer Modelle mit einflie\u00dfen zu lassen. So pr\u00e4sentiert das Unternehmen heute das\u00a0<strong>Pedal-Gokart Berg Vision<\/strong>, das erste von vielen elektrischen Kettcars. Ausgestattet mit vielen neuen Funktionen revolutioniert das elektrische Kettcar den Markt und wird dadurch nicht zu f\u00fcr Kinder zu einem beliebten Spielzeug, sondern tats\u00e4chlich auf f\u00fcr Jugendliche und Erwachsene.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/tUJbBboOmkg\" width=\"655\" height=\"368\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<h2>Ein modernes Tretauto mit viel Technik<\/h2>\n<p>Das k\u00fcrzlich vorgestellte elektrische Kettcar \u201eBerg Vision\u201c der niederl\u00e4ndischen Firma Berg Toys, welches auch \u00fcber\u00a0<a title=\"Gokart-Profi\" href=\"https:\/\/gokart-profi.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fachh\u00e4ndler f\u00fcr Gokarts in Deutschland<\/a>\u00a0bezogen werden kann, ist technisch auf dem neusten Stand und hat auch \u00e4u\u00dferlich nicht mehr viel mit dem rudiment\u00e4ren Stangen-Design der ersten Kettcar-Modelle gemein.<\/p>\n<p>Das elektrische Gokart besitzt viele Funktionen, die \u00fcber einen Bordcomputer gesteuert werden k\u00f6nnen. Zudem verf\u00fcgt es \u00fcber eine Mittelbremsscheibe, der elektrischen Tretunterst\u00fctzung, f\u00fcnf G\u00e4nge und ein Lichtsystem. Damit l\u00e4sst das Kettcar von morgen schon heute keine W\u00fcnsche offen.<\/p>\n<p>Die sportliche und moderne Optik verdankt das neue E-Gokart \u00fcbrigens dem ber\u00fchmten Industriedesigner Giorgio Giugiaro, der es mit seinem Entwurf schaffte, genau den Zahn der Zeit zu treffen.<\/p>\n<h2>Elektromotor erm\u00f6glicht Spitzengeschwindigkeiten von bis zu 45 km\/h<\/h2>\n<p>Der eingebaute 250-Watt-Elektromoter unterst\u00fctz, ganz \u00e4hnlich wie bei einem eBike, den Fahrer dass Kettcars beim Tritt in die Pedalen und vereinfacht so die Anstrengungen und erh\u00f6ht zudem die Geschwindigkeiten. Laut Herstellerangaben soll das elektrische Kettcar bis 45 km\/h schnell fahren k\u00f6nnen.<\/p>\n<p>Auskunft \u00fcber die aktuelle Geschwindigkeit, \u00fcber die verbleibende Reichweite der herausnehmbaren Akkus sowie \u00fcber die zur\u00fcckgelegte Distanz gibt das mittig platzierte Display. Der Fahrer kann zudem zwischen f\u00fcnf unterschiedlichen Fahrstufen w\u00e4hlen. Zudem ist das F\u00fcnfgang-Getriebe mit einem Differential ausgestattet, welches f\u00fcr eine angenehmen und gleichm\u00e4\u00dfige Kraft\u00fcbertragung auf die beiden Hinterr\u00e4der sorgt.<\/p>\n<p>Am Lenkrad l\u00e4sst sich zudem die Fahrtrichtung sowie die komplette Beleuchtungsanlage wie Standlicht, Fernlicht und Blinker, leicht erreichbar steuern.<\/p>\n<p>Durch die verh\u00e4ltnism\u00e4\u00dfig hohen Geschwindigkeiten eignen sich die leistungsstarken elektrischen Kettcars jedoch nicht mehr f\u00fcr kleine Kinder. Daf\u00fcr sind sie bei Jugendlichen und Erwachsenen umso beliebter.<\/p>\n<p>Quelle:<a href=\"https:\/\/www.forschung-und-wissen.de\/nachrichten\/technik\/das-klassische-kettcar-wird-elektrisch-13374288\">Das klassische Kettcar wird elektrisch (forschung-und-wissen.de)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[503],"tags":[],"class_list":["post-11750","post","type-post","status-publish","format-standard","hentry","category-industrienachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/\" \/>\n<meta property=\"og:site_name\" content=\"\u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-23T02:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DPC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DPC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/\",\"url\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/\",\"name\":\"Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/battery9999.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg\",\"datePublished\":\"2021-02-23T02:43:35+00:00\",\"author\":{\"@id\":\"https:\/\/battery9999.com\/#\/schema\/person\/0b9917bf37d9832a82f648a24def18a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage\",\"url\":\"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg\",\"contentUrl\":\"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/battery9999.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das klassische Kettcar wird elektrisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/battery9999.com\/#website\",\"url\":\"https:\/\/battery9999.com\/\",\"name\":\"\u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"description\":\"\u5c08\u696d\u96fb\u6c60\u7d44\u8a2d\u8a08\/\u751f\u7522\/\u88fd\u9020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/battery9999.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/battery9999.com\/#\/schema\/person\/0b9917bf37d9832a82f648a24def18a2\",\"name\":\"DPC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/battery9999.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a258145ae53eacd7bcbebe15acef782?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a258145ae53eacd7bcbebe15acef782?s=96&d=mm&r=g\",\"caption\":\"DPC\"},\"url\":\"https:\/\/battery9999.com\/de\/author\/dpc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/","og_locale":"de_DE","og_type":"article","og_title":"Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8","og_url":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/","og_site_name":"\u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8","article_published_time":"2021-02-23T02:43:35+00:00","og_image":[{"width":990,"height":580,"url":"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar.jpg","type":"image\/jpeg"}],"author":"DPC","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DPC","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/","url":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/","name":"Das klassische Kettcar wird elektrisch - \u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8","isPartOf":{"@id":"https:\/\/battery9999.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage"},"image":{"@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage"},"thumbnailUrl":"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg","datePublished":"2021-02-23T02:43:35+00:00","author":{"@id":"https:\/\/battery9999.com\/#\/schema\/person\/0b9917bf37d9832a82f648a24def18a2"},"breadcrumb":{"@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#primaryimage","url":"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg","contentUrl":"https:\/\/battery9999.com\/wp-content\/uploads\/2021\/02\/elektro-kettcar-300x176.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/battery9999.com\/de\/das-klassische-kettcar-wird-elektrisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/battery9999.com\/de\/"},{"@type":"ListItem","position":2,"name":"Das klassische Kettcar wird elektrisch"}]},{"@type":"WebSite","@id":"https:\/\/battery9999.com\/#website","url":"https:\/\/battery9999.com\/","name":"\u660c\u8467\u80a1\u4efd\u6709\u9650\u516c\u53f8","description":"\u5c08\u696d\u96fb\u6c60\u7d44\u8a2d\u8a08\/\u751f\u7522\/\u88fd\u9020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/battery9999.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/battery9999.com\/#\/schema\/person\/0b9917bf37d9832a82f648a24def18a2","name":"DPC","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/battery9999.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a258145ae53eacd7bcbebe15acef782?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a258145ae53eacd7bcbebe15acef782?s=96&d=mm&r=g","caption":"DPC"},"url":"https:\/\/battery9999.com\/de\/author\/dpc\/"}]}},"_links":{"self":[{"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/posts\/11750"}],"collection":[{"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/comments?post=11750"}],"version-history":[{"count":1,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/posts\/11750\/revisions"}],"predecessor-version":[{"id":11752,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/posts\/11750\/revisions\/11752"}],"wp:attachment":[{"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/media?parent=11750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/categories?post=11750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/battery9999.com\/de\/wp-json\/wp\/v2\/tags?post=11750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}